{"id":17502,"date":"2026-02-10T18:58:50","date_gmt":"2026-02-10T15:58:50","guid":{"rendered":"https:\/\/wolfvapekw.com\/?post_type=product&#038;p=17502"},"modified":"2026-02-11T15:02:54","modified_gmt":"2026-02-11T12:02:54","slug":"%d9%86%d9%83%d9%87%d8%a9-%d8%a7%d9%88%d8%b1%d9%8a%d9%88","status":"publish","type":"product","link":"https:\/\/wolfvapekw.com\/en\/product\/%d9%86%d9%83%d9%87%d8%a9-%d8%a7%d9%88%d8%b1%d9%8a%d9%88\/","title":{"rendered":"\u0646\u0643\u0647\u0629 \u0627\u0648\u0631\u064a\u0648"},"content":{"rendered":"<ul>\n<li>\u0627\u0644\u0628\u0631\u0627\u0646\u062f: \u0645\u0633\u062a\u0631 \u0645\u0627\u0644\u062a\u0633 (Mr. Malts Flurry&#8217;s).<\/li>\n<li>\u0627\u0644\u0646\u0643\u0647\u0629: \u0643\u0648\u0643\u064a\u0632 \u0623\u0646\u062f \u0643\u0631\u064a\u0645 (\u0623\u0648\u0631\u064a\u0648) \u0645\u0639 \u0622\u064a\u0633 \u0643\u0631\u064a\u0645.<\/li>\n<li>\u0627\u0644\u0646\u0648\u0639: \u0641\u0631\u064a \u0628\u064a\u0633 (Free Base).<\/li>\n<li>\u0627\u0644\u062d\u062c\u0645: 60 \u0645\u0644 (60ML).<\/li>\n<li>\u0646\u0633\u0628\u0629 \u0627\u0644\u0646\u064a\u0643\u0648\u062a\u064a\u0646: \u0645\u062a\u0648\u0641\u0631\u0629 \u0628\u062a\u0631\u0643\u064a\u0632 2mg.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>\u0637\u0639\u0645 &#8220;\u0627\u0644\u0645\u0627\u0643 \u0641\u0644\u0648\u0631\u064a&#8221; \u0648\u0627\u0644\u0622\u064a\u0633 \u0643\u0631\u064a\u0645 \u0645\u0639 \u0642\u0637\u0639 \u0627\u0644\u0623\u0648\u0631\u064a\u0648. \u0646\u0643\u0647\u0629 \u0641\u0631\u064a \u0628\u064a\u0633 (Freebase) \u0628\u062d\u062c\u0645 60 \u0645\u0644\u060c \u0645\u064a\u0643\u0633 \u0628\u0627\u0631\u062f \u0648\u0643\u0631\u064a\u0645\u064a \u064a\u0633\u0631\u0633\u062d.<\/p>","protected":false},"featured_media":17503,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[462],"product_cat":[361,473],"product_tag":[],"class_list":{"0":"post-17502","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-vapertreats","7":"product_cat-eliquids","8":"product_cat-freebase","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple","15":"entry","16":"content-bg","17":"loop-entry"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/product\/17502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/comments?post=17502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/media\/17503"}],"wp:attachment":[{"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/media?parent=17502"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/product_brand?post=17502"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/product_cat?post=17502"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wolfvapekw.com\/en\/wp-json\/wp\/v2\/product_tag?post=17502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}